{"id":1447,"date":"2020-05-13T15:29:09","date_gmt":"2020-05-13T15:29:09","guid":{"rendered":"https:\/\/wizard-technology.com\/avis-legal\/"},"modified":"2021-02-02T12:12:37","modified_gmt":"2021-02-02T12:12:37","slug":"avis-legal","status":"publish","type":"page","link":"https:\/\/wizard-technology.com\/fr\/avis-legal\/","title":{"rendered":"Avis l\u00e9gal"},"content":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h1><strong>AVIS L\u00c9GAL<\/strong><\/h1>\n<p><strong><u>Avis l\u00e9gal et informations sur les conditions d\u2019utilisation du site<\/u><\/strong><\/p>\n<p><strong><u>Donn\u00e9es d\u2019identification du propri\u00e9taire du site web<\/u><\/strong><\/p>\n<p>En conformit\u00e9 avec l\u2019obligation d\u2019information pr\u00e9vue \u00e0 l\u2019article 10 de la loi 34\/2002 du 11 juillet sur les Services de la Soci\u00e9t\u00e9 de l\u2019Information et du Commerce \u00c9lectronique, LEMAR LEBEN GROUP,S.L.\u00a0 (d\u00e9sormais, \u201cLEMAR\u201d) et en tant que propri\u00e9taire du site web www. wizard-technology.com , proc\u00e8de \u00e0 la communication des donn\u00e9es d\u2019identification requises par la norme vis\u00e9e :<\/p>\n<p><strong>Nom de l\u2019entreprise : LEMAR LEBEN GROUP,S.L.<\/strong><\/p>\n<p><strong>Adresse de l\u2019entreprise : CALLE EN PROYECTO SN. POLIGONO INDUSTRIAL 2. 46134 FOIOS- VALENCIA<\/strong><\/p>\n<p><strong>CIF : B-46.09.67.15<\/strong><\/p>\n<p><strong>Adresse \u00e9lectronique : lemar@lemarleben.com<\/strong><\/p>\n<p><strong>Donn\u00e9es d\u2019enregistrement au Registre du Commerce de VALENCE, Volume 199, Folio 230, page n\u00ba4205<\/strong><\/p>\n<p>La pr\u00e9sente information soussigne et r\u00e9glemente les conditions d\u2019utilisation, les limitations de responsabilit\u00e9 et les obligations que les utilisateurs du site web publi\u00e9 sous le nom de domaine\u00a0<a href=\"https:\/\/www.wizard-technology.com\/\">www.wizard-technology.com<\/a>\u00a0\u00a0assument et s\u2019engagent \u00e0 respecter.<\/p>\n<p><strong><u>D\u00e9finitions<\/u><\/strong><\/p>\n<p>\u201cPage\u201d, domaine\u00a0<a href=\"https:\/\/www.wizard-technology.com\/\">www.wizard-technology.com<\/a>\u00a0\u00a0qui est mis \u00e0 la disposition des internautes.<\/p>\n<p>\u201cUtilisateur\u201d, personne physique ou morale qui utilise ou demande un service de communications \u00e9lectroniques accessible au public. (D\u00e9finition contenue dans le Code europ\u00e9en des communications \u00e9lectroniques)<\/p>\n<p>\u201cUtilisateur final\u201d d\u00e9signe un utilisateur qui ne fournit pas de r\u00e9seaux de communications publics ou de services de communications \u00e9lectroniques accessibles au public (d\u00e9finition figurant dans le Code europ\u00e9en des communications \u00e9lectroniques)<\/p>\n<p>\u201cContenu\u201d, sont les pages qui composent l\u2019ensemble du domaine\u00a0<a href=\"https:\/\/www.wizard-technology.com\/\">www.wizard-technology.com<\/a>\u00a0qui constituent l\u2019information et les services que\u00a0<strong>LEMAR LEBEN GROUP,SL.<\/strong>\u00a0met \u00e0 la disposition des utilisateurs d\u2019Internet. Ces pages contiennent les messages, textes, photographies, graphiques, ic\u00f4nes, logos, technologie, liens, textures, dessins, fichiers de son et\/ou d\u2019images, enregistrements, logiciels, pr\u00e9sentation, conception graphique et codes sources et, en g\u00e9n\u00e9ral, tout type de mat\u00e9riel contenu dans la page.<\/p>\n<p>\u201cWeb\u201d, un mot technique qui d\u00e9crit le syst\u00e8me d\u2019acc\u00e8s \u00e0 l\u2019information via Internet, qui est configur\u00e9 au moyen de pages r\u00e9alis\u00e9es avec le langage HTML ou un langage similaire, et de m\u00e9canismes de programmation tels que java, javascript, PHP, ou autres, etc. Dans ces pages con\u00e7ues et publi\u00e9es sous un nom de domaine sont le r\u00e9sultat d\u2019informations que le propri\u00e9taire met \u00e0 la disposition des internautes.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cService de communications \u00e9lectroniques\u201d d\u00e9signe un service g\u00e9n\u00e9ralement fourni contre r\u00e9mun\u00e9ration sur les r\u00e9seaux de communications \u00e9lectroniques (d\u00e9finition figurant dans le Code europ\u00e9en des communications \u00e9lectroniques)<\/p>\n<p>\u201cService d\u2019acc\u00e8s \u00e0 l\u2019internet\u201d : un service de communications \u00e9lectroniques accessible au public qui fournit un acc\u00e8s \u00e0 l\u2019internet et donc une connectivit\u00e9 entre pratiquement tous les points connect\u00e9s \u00e0 l\u2019internet, ind\u00e9pendamment de la technologie de r\u00e9seau et des \u00e9quipements terminaux utilis\u00e9s (d\u00e9finition dans le r\u00e8glement concernant des mesures relatives \u00e0 l\u2019acc\u00e8s \u00e0 un internet ouvert)<\/p>\n<p>\u201cHyperlien\u201d, une technique par laquelle un utilisateur peut naviguer \u00e0 travers diff\u00e9rentes pages du Web, ou de l\u2019Internet, par un simple clic sur le texte, l\u2019ic\u00f4ne, le bouton ou l\u2019indicatif qui contient le lien.<\/p>\n<p>\u201cCookies\u201d, un moyen technique pour \u201ctracer\u201d et suivre la navigation sur les sites web. Il s\u2019agit de petits fichiers texte qui sont \u00e9crits sur l\u2019ordinateur de l\u2019utilisateur. Cette m\u00e9thode a des implications sur la vie priv\u00e9e, c\u2019est pourquoi\u00a0<strong>LEMAR LEBEN GROUP,SL<\/strong>.. donnera une notification opportune et fiable de leur utilisation au moment o\u00f9 ils seront mis en \u0153uvre sur la page.<\/p>\n<p>\u201c\u00c9quipement terminal\u201d : un \u00e9quipement connect\u00e9 directement ou indirectement \u00e0 l\u2019interface d\u2019un r\u00e9seau public de t\u00e9l\u00e9communications pour transmettre, traiter ou recevoir des informations (d\u00e9finition figurant dans la directive 2008\/63 relative \u00e0 la concurrence dans les march\u00e9s des \u00e9quipements terminaux de t\u00e9l\u00e9communications)<\/p>\n<p><strong><u>Conditions g\u00e9n\u00e9rales d\u2019utilisation<\/u><\/strong><\/p>\n<p>L\u2019utilisation de la Page conf\u00e8re la condition d\u2019utilisateur de la Page, personne physique ou morale, et implique obligatoirement l\u2019acceptation pleine, enti\u00e8re et sans r\u00e9serve de chacune des clauses et conditions g\u00e9n\u00e9rales incluses dans l\u2019Avis L\u00e9gal. Si l\u2019utilisateur final n\u2019est pas d\u2019accord avec les clauses et conditions d\u2019utilisation de ces mentions l\u00e9gales, il s\u2019abstiendra d\u2019utiliser la page.<\/p>\n<p>Le pr\u00e9sent avis l\u00e9gal est sujet \u00e0 des modifications et des mises \u00e0 jour, de sorte que la version publi\u00e9e par\u00a0<strong>LEMAR LEBEN GROUP, SL.<\/strong>\u00a0peut \u00eatre diff\u00e9rente \u00e0 chaque fois que l\u2019utilisateur acc\u00e8de au site. Par cons\u00e9quent, l\u2019utilisateur final doit lire l\u2019avis juridique chaque fois qu\u2019il acc\u00e8de \u00e0 la page.<\/p>\n<p>A travers cette page,\u00a0<a href=\"https:\/\/www.wizard-technology.com\/\">www.wizard-technology.com<\/a>\u00a0 fournit aux utilisateurs finaux l\u2019acc\u00e8s et l\u2019utilisation de divers contenus publi\u00e9s sur Internet par\u00a0<strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0ou par des tiers autoris\u00e9s.<\/p>\n<p>L\u2019utilisateur final est oblig\u00e9 et s\u2019engage \u00e0 utiliser la Page et les Contenus conform\u00e9ment \u00e0 la l\u00e9gislation en vigueur, \u00e0 l\u2019avis l\u00e9gal et \u00e0 tout autre avis ou instruction qui lui est communiqu\u00e9, soit par le biais de cet avis l\u00e9gal, soit \u00e0 tout autre endroit dans les Contenus qui composent la Page, ainsi qu\u2019aux r\u00e8gles de coexistence, de moralit\u00e9 et aux bonnes coutumes g\u00e9n\u00e9ralement accept\u00e9es.<\/p>\n<p>Dans ce but, l\u2019utilisateur final est oblig\u00e9 et s\u2019engage \u00e0 NE PAS utiliser l\u2019un quelconque des Contenus \u00e0 des fins ou effets illicites, interdits dans l\u2019Avis L\u00e9gal ou par la l\u00e9gislation en vigueur, pr\u00e9judiciables aux droits et int\u00e9r\u00eats de tiers, ou qui pourraient de quelque mani\u00e8re que ce soit endommager, d\u00e9sactiver, surcharger, d\u00e9t\u00e9riorer ou emp\u00eacher l\u2019utilisation normale des Contenus, de l\u2019\u00e9quipement informatique ou des documents, fichiers et tout type de contenus stock\u00e9s dans tout \u00e9quipement informatique appartenant ou contract\u00e9 par\u00a0<strong>LEMAR LEBEN GROUP,S.L.,<\/strong>\u00a0d\u2019autres utilisateurs ou de tout utilisateur d\u2019Internet (mat\u00e9riel et logiciel).<\/p>\n<p>L\u2019Utilisateur final accepte et s\u2019engage \u00e0 ne pas transmettre, diffuser ou mettre \u00e0 disposition de tiers tout type de mat\u00e9riel contenu sur le Site, tel que des informations, textes, donn\u00e9es, contenus, messages, graphiques, dessins, fichiers sons et\/ou images, photographies, enregistrements, logiciels, logos, marques, ic\u00f4nes, technologie, photographies, logiciels, liens, conception graphique et codes sources, ou tout autre mat\u00e9riel auquel il a acc\u00e8s en sa qualit\u00e9 d\u2019Utilisateur du Site, sans que cette liste soit limitative.<\/p>\n<p>En outre, conform\u00e9ment \u00e0 cela, l\u2019utilisateur final ne peut pas :<\/p>\n<ul>\n<li>Reproduire, copier, distribuer, mettre \u00e0 disposition ou de toute autre mani\u00e8re communiquer publiquement, transformer ou modifier les Contenus, sauf si vous avez l\u2019autorisation \u00e9crite explicite de\u00a0<strong>LEMAR LEBEN GROUP,SL.,<\/strong>\u00a0qui d\u00e9tient les droits correspondants, ou que cela est l\u00e9galement autoris\u00e9.<\/li>\n<\/ul>\n<ul>\n<li>Effacer, manipuler ou alt\u00e9rer de quelque fa\u00e7on que ce soit les droits d\u2019auteur et autres donn\u00e9es identifiant la propri\u00e9t\u00e9 de\u00a0<strong>LEMAR LEBEN GROUP,SL.<\/strong>\u00a0ou de ses propri\u00e9taires, les empreintes digitales et\/ou les identificateurs num\u00e9riques, ou tout autre moyen technique \u00e9tabli pour leur reconnaissance.<\/li>\n<\/ul>\n<p>L\u2019Utilisateur final doit s\u2019abstenir d\u2019obtenir et m\u00eame d\u2019essayer d\u2019obtenir les Contenus en utilisant des moyens ou des proc\u00e9dures autres que ceux qui, selon le cas, ont \u00e9t\u00e9 mis \u00e0 sa disposition \u00e0 cette fin ou ont \u00e9t\u00e9 indiqu\u00e9s \u00e0 cette fin sur les pages web o\u00f9 se trouvent les Contenus ou, en g\u00e9n\u00e9ral, ceux qui sont normalement utilis\u00e9s sur Internet \u00e0 cette fin, \u00e0 condition qu\u2019ils n\u2019impliquent pas un risque de dommage ou de d\u00e9sactivation de la Page, et\/ou des Contenus.<\/p>\n<p><strong><u>Propri\u00e9t\u00e9 intellectuelle<\/u><\/strong><\/p>\n<p>Toutes les marques, noms commerciaux ou signes distinctifs de toute nature qui apparaissent sur le site Web sont la propri\u00e9t\u00e9 de\u00a0<strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0ou, le cas \u00e9ch\u00e9ant, de tiers qui en ont autoris\u00e9 l\u2019utilisation, sans que l\u2019utilisation ou l\u2019acc\u00e8s au site Web et\/ou aux Contenus n\u2019attribue \u00e0 l\u2019utilisateur un quelconque droit sur lesdites marques, noms commerciaux et\/ou signes distinctifs, et sans qu\u2019il soit entendu qu\u2019aucun des droits d\u2019exploitation existant ou pouvant exister sur lesdits Contenus n\u2019ait \u00e9t\u00e9 c\u00e9d\u00e9 \u00e0 l\u2019utilisateur.<\/p>\n<p>De m\u00eame, les Contenus sont la propri\u00e9t\u00e9 intellectuelle de\u00a0<strong>LEMAR LEBEN GROUPE,S.L.,<\/strong>\u00a0ou de tiers le cas \u00e9ch\u00e9ant, par cons\u00e9quent, les droits de Propri\u00e9t\u00e9 Intellectuelle sont d\u00e9tenus par\u00a0<strong>LEMAR LEBEN GROUPE,S.L.<\/strong>\u00a0ou par des tiers qui ont autoris\u00e9 leur utilisation, qui ont le droit exclusif de les exploiter de quelque fa\u00e7on que ce soit et, en particulier, les droits de reproduction, distribution, communication publique et transformation.<\/p>\n<p>L\u2019utilisation non autoris\u00e9e des informations contenues sur ce site web, ainsi que toute violation des droits de propri\u00e9t\u00e9 intellectuelle ou industrielle de\u00a0<strong>LEMAR LEBEN GROUP,SL.<\/strong>\u00a0ou des tiers inclus dans le site web qui ont fourni des contenus, donnera lieu aux responsabilit\u00e9s l\u00e9galement \u00e9tablies.<\/p>\n<p><strong><u>Hyperliens<\/u><\/strong><\/p>\n<p>Les personnes qui ont l\u2019intention d\u2019\u00e9tablir des hyperliens entre leur site web et le Site doivent observer et respecter les conditions suivantes :<\/p>\n<ul>\n<li>Aucune autorisation pr\u00e9alable n\u2019est requise lorsque l\u2019hyperlien permet uniquement d\u2019acc\u00e9der \u00e0 la page d\u2019accueil, mais vous ne pouvez pas le reproduire de quelque mani\u00e8re que ce soit. Toute autre forme de lien hypertexte n\u00e9cessitera l\u2019autorisation \u00e9crite expresse et sans \u00e9quivoque de\u00a0<strong>LEMAR LEBEN GROUP,SL<\/strong>\u00a0.<\/li>\n<li>Aucun \u201cframe\u201d ne sera cr\u00e9\u00e9 avec les pages web ou sur les pages web de\u00a0<strong>LEMAR LEBEN GROUP,S.L.<\/strong><\/li>\n<li>Aucune d\u00e9claration ou indication fausse, inexacte ou injurieuse ne sera faite sur\u00a0<strong>LEMAR LEBEN GROUP, S.L.,<\/strong>\u00a0ses directeurs, employ\u00e9s ou collaborateurs, ou les personnes qui sont li\u00e9es \u00e0 la Page pour quelque raison que ce soit, ou les Utilisateurs de la Page, ou le Contenu fourni.<\/li>\n<li>Il ne sera pas d\u00e9clar\u00e9 ou laiss\u00e9 entendre que LEMAR LEBEN GROUP,S.L. a autoris\u00e9 l\u2019Hyperlien ou qu\u2019il a supervis\u00e9 ou assum\u00e9 de quelque mani\u00e8re que ce soit les Contenus offerts ou mis \u00e0 disposition sur la page web dans laquelle l\u2019Hyperlien est \u00e9tabli.<\/li>\n<li>La page Web o\u00f9 l\u2019hyperlien est \u00e9tabli ne peut contenir que ce qui est strictement n\u00e9cessaire pour identifier la destination de l\u2019hyperlien.<\/li>\n<\/ul>\n<ul>\n<li>La page web dans laquelle l\u2019hyperlien est \u00e9tabli ne doit pas contenir d\u2019informations ou de contenus illicites, contraires \u00e0 la morale, aux bonnes m\u0153urs et \u00e0 l\u2019ordre public, ni de contenus contraires aux droits de tiers.<\/li>\n<\/ul>\n<p><strong><u>Politique des cookies<\/u><\/strong><\/p>\n<p>Les cookies sont les moyens techniques permettant de \u201ctracer\u201d et de suivre la navigation sur les sites web. Il s\u2019agit de petits fichiers texte qui sont \u00e9crits sur l\u2019ordinateur de l\u2019utilisateur. Cette m\u00e9thode a des implications sur la vie priv\u00e9e, c\u2019est pourquoi\u00a0<strong>LEMAR LEBEN GROUP,SL.<\/strong>\u00a0vous informe qu\u2019elle peut utiliser des cookies afin d\u2019\u00e9tablir des statistiques sur l\u2019utilisation du site web ainsi que pour identifier le PC de l\u2019utilisateur, permettant de le reconna\u00eetre lors de visites ult\u00e9rieures. Dans tous les cas, l\u2019utilisateur peut configurer son navigateur de mani\u00e8re \u00e0 ne pas autoriser l\u2019utilisation de cookies lors de ses visites sur le site web.<\/p>\n<p>Sur\u00a0<strong>www.wizard-technology.com<\/strong>, nous utilisons des cookies dans le but de vous offrir un meilleur service et une meilleure exp\u00e9rience de navigation. Nous souhaitons vous informer de mani\u00e8re claire et pr\u00e9cise sur les cookies que nous utilisons, en pr\u00e9cisant ci-dessous ce qu\u2019est un cookie, \u00e0 quoi il sert, \u00e0 quoi il sert et comment vous pouvez les configurer ou les d\u00e9sactiver si vous le souhaitez.<\/p>\n<p>Conform\u00e9ment \u00e0 la r\u00e9glementation espagnole r\u00e9gissant l\u2019utilisation des cookies dans le cadre de la fourniture de services de communications \u00e9lectroniques, \u00e9nonc\u00e9e dans le d\u00e9cret-loi royal 13\/2012 du 30 mars, nous vous informons des cookies utilis\u00e9s sur le site web\u00a0<strong>www.wizard-technology.com<\/strong>\u00a0(ci-apr\u00e8s le \u201csite web\u201d) et de la raison de leur utilisation. De m\u00eame,\u00a0<strong>LEMAR LEBEN GROUP,SL<\/strong>. vous informe qu\u2019en naviguant sur le site web vous donnez votre consentement pour les utiliser.<\/p>\n<p>Les cookies utilis\u00e9s dans notre site Web peuvent \u00eatre propres ou de tiers et nous permettent de stocker et d\u2019acc\u00e9der \u00e0 des informations relatives \u00e0 la langue, au type de navigateur utilis\u00e9 et \u00e0 d\u2019autres caract\u00e9ristiques g\u00e9n\u00e9rales pr\u00e9d\u00e9finies par l\u2019utilisateur, ainsi que de suivre et d\u2019analyser l\u2019activit\u00e9 qui se d\u00e9roule, dans le but d\u2019apporter des am\u00e9liorations et de fournir nos services de mani\u00e8re plus efficace et personnalis\u00e9e.<\/p>\n<p>L\u2019utilisation de cookies offre de nombreux avantages dans la prestation de services de la soci\u00e9t\u00e9 de l\u2019information, car, entre autres : elle facilite la navigation de l\u2019utilisateur sur le site web et l\u2019acc\u00e8s aux diff\u00e9rents services qu\u2019il propose ; elle emp\u00eache l\u2019utilisateur de configurer des caract\u00e9ristiques g\u00e9n\u00e9rales pr\u00e9d\u00e9finies \u00e0 chaque fois qu\u2019il acc\u00e8de au site web ; elle favorise l\u2019am\u00e9lioration du fonctionnement et des services fournis par le biais du site web, apr\u00e8s l\u2019analyse correspondante des informations obtenues gr\u00e2ce aux cookies install\u00e9s.<\/p>\n<p>Cependant, vous pouvez configurer votre navigateur, en acceptant ou en refusant tous les cookies, ou en s\u00e9lectionnant ceux dont l\u2019installation est autoris\u00e9e et ceux qui ne le sont pas, en suivant l\u2019une des proc\u00e9dures suivantes, selon le navigateur utilis\u00e9 :<\/p>\n<ul>\n<li>Google Chrome (dans le menu Outils) : Param\u00e8tres &gt; Afficher les options avanc\u00e9es &gt; Confidentialit\u00e9 (Param\u00e8tres du contenu) &gt; Cookies. En savoir plus sur Google Chrome:\u00a0<a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647\">http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647<\/a><\/li>\n<li>Microsoft Internet Explorer (dans le menu Outils) : Options Internet &gt; Confidentialit\u00e9 &gt; Avanc\u00e9. En savoir plus sur Internet Explorer:\u00a0<a href=\"http:\/\/windows.microsoft.com\/es-es\/windows7\/how-to-manage-cookies-in-internet-explorer-9\">http:\/\/windows.microsoft.com\/es-es\/windows7\/how-to-manage-cookies-in-internet-explorer-9<\/a><\/li>\n<li>Firefox : Options &gt; Confidentialit\u00e9 &gt; Cookies. En savoir plus sur Firefox:\u00a0<a href=\"http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we\">http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we<\/a><\/li>\n<li>Safari, iPad et iPhone : Pr\u00e9f\u00e9rences &gt; Confidentialit\u00e9. En savoir plus sur Safari, iPad et iPhone:\u00a0<a href=\"http:\/\/support.apple.com\/kb\/ph5042\">http:\/\/support.apple.com\/kb\/ph5042<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><u>Disponibilit\u00e9 de la page<\/u><\/strong><\/p>\n<p><strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0 ne garantit pas l\u2019inexistence d\u2019interruptions ou d\u2019erreurs dans l\u2019acc\u00e8s \u00e0 la Page, \u00e0 son Contenu, ni qu\u2019elle soit mise \u00e0 jour, bien qu\u2019elle fasse ses meilleurs efforts pour les \u00e9viter, les corriger ou les actualiser. Par cons\u00e9quent,\u00a0<strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0ne sera pas responsable des dommages ou des pertes de toute nature caus\u00e9s \u00e0 l\u2019utilisateur final par des pannes ou des d\u00e9connexions dans les r\u00e9seaux de t\u00e9l\u00e9communications qui entra\u00eenent la suspension, l\u2019annulation ou l\u2019interruption du service du Portail pendant la fourniture de celui-ci ou avant.<\/p>\n<p><strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0exclut, avec les exceptions pr\u00e9vues par la l\u00e9gislation en vigueur, toute responsabilit\u00e9 pour les dommages et int\u00e9r\u00eats de toute nature qui pourraient \u00eatre dus au manque de disponibilit\u00e9, de continuit\u00e9 ou de qualit\u00e9 du fonctionnement du Site et de ses Contenus, au non-respect de l\u2019attente d\u2019utilit\u00e9 que les utilisateurs pourraient avoir attribu\u00e9e au Site et \u00e0 ses Contenus.<\/p>\n<p>La fonction des Hyperliens qui apparaissent sur ce site Web est exclusivement d\u2019informer l\u2019utilisateur de l\u2019existence d\u2019autres sites Web qui contiennent des informations sur le sujet. Ces hyperliens ne constituent en aucun cas une suggestion ou une recommandation quelconque.\u00a0<strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0n\u2019est pas responsable du contenu de ces pages li\u00e9es, du fonctionnement ou de l\u2019utilit\u00e9 des Hyperliens ou du r\u00e9sultat de ces liens, ni ne garantit l\u2019absence de virus ou d\u2019autres \u00e9l\u00e9ments dans ces derniers qui pourraient provoquer des alt\u00e9rations dans le syst\u00e8me informatique (mat\u00e9riel et logiciel), les documents ou les fichiers de l\u2019utilisateur, excluant toute responsabilit\u00e9 pour les dommages de toute nature caus\u00e9s \u00e0 l\u2019utilisateur pour cette raison.<\/p>\n<p>L\u2019acc\u00e8s \u00e0 la Page n\u2019implique aucune obligation de la part de\u00a0<strong>LEMAR LEBEN GROUP,S.L<\/strong>. de v\u00e9rifier l\u2019absence de virus, de vers ou de tout autre \u00e9l\u00e9ment informatique nuisible. L\u2019utilisateur est responsable, dans tous les cas, de la disponibilit\u00e9 des outils appropri\u00e9s pour la d\u00e9tection et la d\u00e9sinfection des programmes informatiques nuisibles, par cons\u00e9quent,\u00a0<strong>LEMAR LEBEN GROUP,S.L<\/strong>. n\u2019est pas responsable des \u00e9ventuelles erreurs de s\u00e9curit\u00e9 qui pourraient se produire lors de la prestation du service de la Page, ni des \u00e9ventuels dommages qui pourraient \u00eatre caus\u00e9s au syst\u00e8me informatique de l\u2019utilisateur ou de tiers (mat\u00e9riel et logiciel), aux fichiers ou aux documents qui y sont stock\u00e9s, suite \u00e0 la pr\u00e9sence d\u2019un virus dans l\u2019ordinateur utilis\u00e9 par l\u2019utilisateur pour se connecter aux services et aux contenus du Web, \u00e0 un dysfonctionnement du navigateur ou \u00e0 l\u2019utilisation de versions obsol\u00e8tes de celui-ci.<\/p>\n<p><strong><u>Qualit\u00e9 de la page<\/u><\/strong><\/p>\n<p>\u00c9tant donn\u00e9 l\u2019environnement dynamique et changeant de l\u2019information et des services fournis \u00e0 travers la Page,\u00a0<strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0fait ses meilleurs efforts, mais ne garantit pas la totale v\u00e9racit\u00e9, exactitude, fiabilit\u00e9, utilit\u00e9 et\/ou actualit\u00e9 du Contenu.<\/p>\n<p>Les informations contenues dans les pages qui composent ce Portail sont uniquement de nature informative, consultative, informative et publicitaire. En aucun cas, ils n\u2019offrent ou n\u2019ont le caract\u00e8re d\u2019un engagement contraignant ou contractuel.<\/p>\n<p><strong><u>Limitation de responsabilit\u00e9<\/u><\/strong><\/p>\n<p><strong>LEMAR LEBEN GROUP,S.L.\u00a0<\/strong>\u00a0exclut toute responsabilit\u00e9 pour les d\u00e9cisions que l\u2019utilisateur final pourrait prendre sur la base de cette information, ainsi que pour les \u00e9ventuelles erreurs typographiques qui pourraient \u00eatre contenues dans les documents et graphiques de la Page. L\u2019information est sujette \u00e0 d\u2019\u00e9ventuelles modifications p\u00e9riodiques sans pr\u00e9avis de son contenu en raison de l\u2019extension, de l\u2019am\u00e9lioration, de la correction ou de la mise \u00e0 jour du contenu.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Notifications<\/u><\/strong><\/p>\n<p>Toutes les notifications et communications de\u00a0<strong>LEMAR LEBEN GROUP, S.L.<\/strong>\u00a0\u00e0 l\u2019utilisateur final, effectu\u00e9es par quelque moyen que ce soit, seront consid\u00e9r\u00e9es comme effectives \u00e0 toutes fins.<\/p>\n<p><strong><u>Disponibilit\u00e9 du contenu<\/u><\/strong><\/p>\n<p>La fourniture du service de la page et du contenu a, en principe, une dur\u00e9e ind\u00e9termin\u00e9e.\u00a0<strong>LEMAR LEBEN GROUP,S.L<\/strong>. N\u00e9anmoins, il est autoris\u00e9 \u00e0 mettre fin ou \u00e0 suspendre la fourniture du service de la page et\/ou de l\u2019un des contenus \u00e0 tout moment. Chaque fois que cela sera raisonnablement possible, LEMAR LEBEN GROUP,S.L. donnera un pr\u00e9avis de r\u00e9siliation ou de suspension de la Page.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Protection des donn\u00e9es \u00e0 caract\u00e8re personnel<\/u><\/strong><\/p>\n<p><strong>LEMAR LEBEN GROUP,S.L.<\/strong>\u00a0est conscient de l\u2019importance de la confidentialit\u00e9 des donn\u00e9es personnelles et a donc mis en place une politique de traitement des donn\u00e9es visant \u00e0 assurer une s\u00e9curit\u00e9 maximale dans l\u2019utilisation et la collecte de ces donn\u00e9es, en garantissant le respect de la r\u00e9glementation en vigueur en la mati\u00e8re et en configurant cette politique comme l\u2019un des piliers fondamentaux dans les lignes d\u2019action de l\u2019entit\u00e9.<\/p>\n<p>Lors de la navigation sur le site www.wizardozone.es, il est possible que des donn\u00e9es personnelles soient demand\u00e9es par le biais de diff\u00e9rents formulaires pr\u00e9vus \u00e0 cet effet. Ces donn\u00e9es seront incluses dans les fichiers pertinents en fonction de la finalit\u00e9 sp\u00e9cifique pour laquelle elles sont collect\u00e9es.<\/p>\n<p>De cette fa\u00e7on, l\u2019information particuli\u00e8re de chaque traitement de donn\u00e9es sera fournie \u00e0 c\u00f4t\u00e9 de chaque formulaire web, \u00e9tant commun \u00e0 tous les responsables du traitement :\u00a0<strong>LEMAR LEBEN GROUP,S.L<\/strong>. domicili\u00e9 \u00e0 C\/EN PROYECTO SN,. POLIGONO INDUSTRIAL 2, 46134 FOIOS- VALENCIA, ainsi que le lieu et la forme d\u2019exercice des droits d\u2019acc\u00e8s, de rectification, de suppression, de portabilit\u00e9 de leurs donn\u00e9es, ainsi que de limitation ou d\u2019opposition \u00e0 leur traitement, qui doivent \u00eatre formalis\u00e9s par une communication \u00e9crite \u00e0 l\u2019adresse indiqu\u00e9e ci-dessus, comprenant une copie de la carte d\u2019identit\u00e9 ou d\u2019un document d\u2019identification \u00e9quivalent.<\/p>\n<p>Dans le cas o\u00f9 vous fournissez vos donn\u00e9es par le biais d\u2019un message \u00e9lectronique, celles-ci feront partie d\u2019un fichier dont la finalit\u00e9 sera la gestion de la demande ou du commentaire que vous nous faites, le reste des points indiqu\u00e9s au paragraphe pr\u00e9c\u00e9dent \u00e9tant applicable.<\/p>\n<p>De m\u00eame, les conditions g\u00e9n\u00e9rales d\u2019engagement des services de\u00a0<strong>LEMAR LEBEN GROUP,SL.<\/strong>\u00a0d\u00e9velopp\u00e9es par cette derni\u00e8re dans le cas o\u00f9 vous concluriez un contrat avec l\u2019une d\u2019entre elles.<\/p>\n<p>D\u2019autre part,\u00a0<strong>LEMAR LEBEN GROUP,SL.<\/strong>\u00a0a mis en place les mesures techniques et organisationnelles n\u00e9cessaires pour \u00e9viter la perte, le mauvais usage, l\u2019alt\u00e9ration, l\u2019acc\u00e8s non autoris\u00e9 et le vol des donn\u00e9es personnelles que les int\u00e9ress\u00e9s peuvent fournir suite \u00e0 l\u2019acc\u00e8s aux diff\u00e9rentes sections du site web\u00a0<a href=\"https:\/\/www.wizard-technology.com\/\">www.wizard-technology.com<\/a>\u00a0\u00a0en appliquant les mesures de s\u00e9curit\u00e9 pr\u00e9vues par le r\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil, du 27 avril 2016, relatif \u00e0 la protection des personnes physiques \u00e0 l\u2019\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es (r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es \u2013 RGPD).<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>Juridiction<\/u><\/strong><\/p>\n<p>Pour toute question concernant l\u2019interpr\u00e9tation, l\u2019application et le respect du pr\u00e9sent avis juridique, ainsi que pour toute r\u00e9clamation pouvant d\u00e9couler de son utilisation, toutes les parties concern\u00e9es se soumettent aux juges et tribunaux de Valence, en renon\u00e7ant express\u00e9ment \u00e0 toute autre juridiction qui pourrait leur correspondre.<\/p>\n<p><strong><u>L\u00e9gislation applicable<\/u><\/strong><\/p>\n<p>L\u2019avis l\u00e9gal est r\u00e9gi par le droit espagnol.<\/p>\n<p>Tous droits r\u00e9serv\u00e9s par les lois et les trait\u00e9s internationaux sur la propri\u00e9t\u00e9 intellectuelle. Il est express\u00e9ment interdit de le copier, de le reproduire ou de le diffuser, en tout ou en partie, par quelque moyen que ce soit.<\/p>\n<p>nissez. C\u2019est pourquoi, en plus d\u2019\u00eatre membres fondateurs de l\u2019@ECE (Association espagnole de commerce \u00e9lectronique), nous sommes \u00e9galement membres de Confianza Online, un syst\u00e8me de r\u00e9solution des litiges qui peuvent survenir entre les consommateurs et les entreprises dans le domaine du commerce \u00e9lectronique et de la publicit\u00e9 interactive, soutenu par un grand nombre d\u2019associations d\u2019entreprises, l\u2019Institut National de la Consommation, l\u2019Agence Espagnole de Protection des Donn\u00e9es et le Minist\u00e8re des Sciences et de la Technologie.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text] AVIS L\u00c9GAL Avis l\u00e9gal et informations sur les conditions d\u2019utilisation du site Donn\u00e9es d\u2019identification du propri\u00e9taire du<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1000,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1447","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avis l\u00e9gal | Wizard<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis l\u00e9gal | Wizard\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text] AVIS L\u00c9GAL Avis l\u00e9gal et informations sur les conditions d\u2019utilisation du site Donn\u00e9es d\u2019identification du propri\u00e9taire du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wizard-technology.com\/fr\/avis-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Wizard\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WizardOzone\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-02T12:12:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/avis-legal\\\/\",\"url\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/avis-legal\\\/\",\"name\":\"Avis l\u00e9gal | Wizard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-05-13T15:29:09+00:00\",\"dateModified\":\"2021-02-02T12:12:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/avis-legal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/avis-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/avis-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis l\u00e9gal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/\",\"name\":\"Wizard\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/#organization\",\"name\":\"Wizard Technology\",\"url\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wizard-technology.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Wizardozone-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/wizard-technology.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Wizardozone-logo-1.png\",\"width\":181,\"height\":60,\"caption\":\"Wizard Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/wizard-technology.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WizardOzone\\\/\",\"https:\\\/\\\/www.instagram.com\\\/wizardozone\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wizard-ozone\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis l\u00e9gal | Wizard","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Avis l\u00e9gal | Wizard","og_description":"[vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_column_text] AVIS L\u00c9GAL Avis l\u00e9gal et informations sur les conditions d\u2019utilisation du site Donn\u00e9es d\u2019identification du propri\u00e9taire du","og_url":"https:\/\/wizard-technology.com\/fr\/avis-legal\/","og_site_name":"Wizard","article_publisher":"https:\/\/www.facebook.com\/WizardOzone\/","article_modified_time":"2021-02-02T12:12:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wizard-technology.com\/fr\/avis-legal\/","url":"https:\/\/wizard-technology.com\/fr\/avis-legal\/","name":"Avis l\u00e9gal | Wizard","isPartOf":{"@id":"https:\/\/wizard-technology.com\/fr\/#website"},"datePublished":"2020-05-13T15:29:09+00:00","dateModified":"2021-02-02T12:12:37+00:00","breadcrumb":{"@id":"https:\/\/wizard-technology.com\/fr\/avis-legal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wizard-technology.com\/fr\/avis-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wizard-technology.com\/fr\/avis-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/wizard-technology.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Avis l\u00e9gal"}]},{"@type":"WebSite","@id":"https:\/\/wizard-technology.com\/fr\/#website","url":"https:\/\/wizard-technology.com\/fr\/","name":"Wizard","description":"","publisher":{"@id":"https:\/\/wizard-technology.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wizard-technology.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wizard-technology.com\/fr\/#organization","name":"Wizard Technology","url":"https:\/\/wizard-technology.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wizard-technology.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wizard-technology.com\/wp-content\/uploads\/2020\/05\/Wizardozone-logo-1.png","contentUrl":"https:\/\/wizard-technology.com\/wp-content\/uploads\/2020\/05\/Wizardozone-logo-1.png","width":181,"height":60,"caption":"Wizard Technology"},"image":{"@id":"https:\/\/wizard-technology.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WizardOzone\/","https:\/\/www.instagram.com\/wizardozone\/","https:\/\/www.linkedin.com\/company\/wizard-ozone\/"]}]}},"_links":{"self":[{"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/pages\/1447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/comments?post=1447"}],"version-history":[{"count":10,"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/pages\/1447\/revisions"}],"predecessor-version":[{"id":7842,"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/pages\/1447\/revisions\/7842"}],"wp:attachment":[{"href":"https:\/\/wizard-technology.com\/fr\/wp-json\/wp\/v2\/media?parent=1447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}